{"id":18727,"date":"2023-04-06T10:00:15","date_gmt":"2023-04-06T14:00:15","guid":{"rendered":"https:\/\/www.northcentralmass.com\/?p=18727"},"modified":"2025-02-02T18:27:41","modified_gmt":"2025-02-02T23:27:41","slug":"north-central-massachusetts-announces-three-year-strategic-plan","status":"publish","type":"post","link":"https:\/\/www.northcentralmass.com\/es\/north-central-massachusetts-announces-three-year-strategic-plan\/","title":{"rendered":"North Central Massachusetts announces three-year strategic plan"},"content":{"rendered":"<div id=\"attachment_18731\" style=\"width: 360px\" class=\"wp-caption alignright\"><a href=\"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-v7.pdf\" target=\"_blank\" rel=\"noopener\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-18731\" class=\"wp-image-18731\" src=\"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-225x300.jpg\" alt=\"NCMCC Strategic Plan 2022-2025\" width=\"350\" height=\"467\" srcset=\"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-225x300.jpg 225w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-772x1030.jpg 772w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-768x1024.jpg 768w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-1152x1536.jpg 1152w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-1536x2048.jpg 1536w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-1125x1500.jpg 1125w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-529x705.jpg 529w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025-450x600.jpg 450w, https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-2025.jpg 1500w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><p id=\"caption-attachment-18731\" class=\"wp-caption-text\">North Central Massachusetts Chamber of Commerce Strategic Plan Overview 2022-2025<\/p><\/div>\n<p><em>Plan aligns with One North Central Regional Economic Development Plan focused on regional prosperity, market opportunities<\/em><\/p>\n<p>The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.<\/p>\n<p>\u201cOur new strategic plan capitalizes upon the successes experienced over the past four years while also acknowledging a significant number of emerging opportunities and challenges currently facing our region,\u201d said Roy Nascimento, President and CEO, North Central Massachusetts Chamber of Commerce. \u201cAt the same time, it incorporates many of the invaluable recommendations of <a href=\"https:\/\/www.northcentralmass.com\/es\/economic-development\/onenorthcentral\/\" target=\"_blank\" rel=\"noopener\">Uno del norte central<\/a>, our comprehensive regional economic development plan commissioned by the Chamber in concert with our local partners and unveiled in 2021.\u201d<\/p>\n<p><strong>The 2023-2025 plan includes five goals focusing on specific areas with accountable metrics and targets:<\/strong><\/p>\n<p><strong>Goal 1:<\/strong> Strengthen the regional economy and improve the overall business climate;<\/p>\n<p><strong>Goal 2:<\/strong> Promote the region as an ideal place to live, work, visit and invest;<\/p>\n<p><strong>Goal 3:<\/strong> Partner with educational, business and non-profit communities to address the region\u2019s growing workforce development needs;<\/p>\n<p><strong>Goal 4:<\/strong> Deepen the region\u2019s understanding of complex issues, identify collaborative solutions and advocate to key decision makers and stakeholders;<\/p>\n<p><strong>Goal 5:<\/strong> Position the Chamber for long-term sustainability and success.<\/p>\n<p>The strategic plan, which was approved by the Chamber Board and its affiliate Boards from North Central Massachusetts Development Corporation and Visit North Central Massachusetts, was prepared via a comprehensive process that included input from members, the Boards, staff and other stakeholders. The new strategic plan complements the One North Central plan while aligning with the Chamber\u2019s advocacy agenda.<\/p>\n<p>\u201cWe made great strides in achieving key goals set forth in our previous plan,\u201d said Nascimento. \u201cFrom launching a localized online jobs resource and a Latinx business initiative to better engage and support Latinx small businesses to securing nearly four million dollars in state, federal and private funding to supporting lending efforts and regional economic development, we are pleased with our work and look forward to continuing the momentum over the next three years.\u201d<\/p>\n<p>Programs and projects will be undertaken with care and consideration of actual resources of the Chamber and its members. The plan is also a fluid document of which the Chamber will update as needed to reflect the changing world.<\/p>\n<div  class='avia-button-wrap av-2cjycn-7b6948bec71a109978cc565658eacc36-wrap avia-button-left  avia-builder-el-0  avia-builder-el-no-sibling'><a href='https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022-v7.pdf'  class='avia-button av-2cjycn-7b6948bec71a109978cc565658eacc36 av-link-btn avia-icon_select-yes-right-icon avia-size-large avia-position-left avia-color-theme-color'  target=\"_blank\"  rel=\"noopener noreferrer\"  aria-label=\"North Central Massachusetts Chamber of Commerce Strategic Plan Overview 2022-2025\"><span class='avia_iconbox_title' >North Central Massachusetts Chamber of Commerce Strategic Plan Overview 2022-2025<\/span><span class='avia_button_icon avia_button_icon_right avia-iconfont avia-font-entypo-fontello' data-av_icon='\ue875' data-av_iconfont='entypo-fontello' ><\/span><\/a><\/div>\n<p>&nbsp;<\/p>\n<hr \/>\n<p class=\"p1\"><em>Chamber of Commerce | North Central Massachusetts | North Central Massachusetts Chamber | North Central Regional Economic Development Plan | North Central Massachusetts Development Corporation | Visit North Central Massachusetts<\/em><\/p>","protected":false},"excerpt":{"rendered":"<p>Plan aligns with One North Central Regional Economic Development Plan focused on regional prosperity, market opportunities The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018. \u201cOur new strategic plan [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":18730,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[],"class_list":["post-18727","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce<\/title>\n<meta name=\"description\" content=\"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.northcentralmass.com\/es\/north-central-massachusetts-announces-three-year-strategic-plan\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce\" \/>\n<meta property=\"og:description\" content=\"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.northcentralmass.com\/es\/north-central-massachusetts-announces-three-year-strategic-plan\/\" \/>\n<meta property=\"og:site_name\" content=\"North Central Massachusetts Chamber of Commerce\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ncmchamber\" \/>\n<meta property=\"article:published_time\" content=\"2023-04-06T14:00:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-02T23:27:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"454\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"northcentralmass\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@ncmchamber\" \/>\n<meta name=\"twitter:site\" content=\"@ncmchamber\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"northcentralmass\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/\"},\"author\":{\"name\":\"northcentralmass\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#\\\/schema\\\/person\\\/d8d3caef0152a831fa2ddb493f900037\"},\"headline\":\"North Central Massachusetts announces three-year strategic plan\",\"datePublished\":\"2023-04-06T14:00:15+00:00\",\"dateModified\":\"2025-02-02T23:27:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/\"},\"wordCount\":488,\"publisher\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/NCMCC-Strategic-Plan-2022.jpg\",\"articleSection\":[\"Chamber News\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/\",\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/\",\"name\":\"North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/NCMCC-Strategic-Plan-2022.jpg\",\"datePublished\":\"2023-04-06T14:00:15+00:00\",\"dateModified\":\"2025-02-02T23:27:41+00:00\",\"description\":\"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/NCMCC-Strategic-Plan-2022.jpg\",\"contentUrl\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/NCMCC-Strategic-Plan-2022.jpg\",\"width\":1200,\"height\":454,\"caption\":\"NCMCC Strategic Plan 2022\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/north-central-massachusetts-announces-three-year-strategic-plan\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.northcentralmass.com\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"North Central Massachusetts announces three-year strategic plan\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#website\",\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/\",\"name\":\"North Central Massachusetts Chamber of Commerce\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.northcentralmass.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#organization\",\"name\":\"North Central Massachusetts Chamber of Commerce\",\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/nccc-yoast-logo.jpg\",\"contentUrl\":\"https:\\\/\\\/www.northcentralmass.com\\\/wp-content\\\/uploads\\\/2023\\\/09\\\/nccc-yoast-logo.jpg\",\"width\":1200,\"height\":600,\"caption\":\"North Central Massachusetts Chamber of Commerce\"},\"image\":{\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ncmchamber\",\"https:\\\/\\\/x.com\\\/ncmchamber\",\"https:\\\/\\\/www.linkedin.com\\\/groups\\\/North-Central-Massachusetts-Chamber-Commerce-8253188\\\/about\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.northcentralmass.com\\\/#\\\/schema\\\/person\\\/d8d3caef0152a831fa2ddb493f900037\",\"name\":\"northcentralmass\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g\",\"caption\":\"northcentralmass\"},\"url\":\"https:\\\/\\\/www.northcentralmass.com\\\/es\\\/author\\\/northcentralmass\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce","description":"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.northcentralmass.com\/es\/north-central-massachusetts-announces-three-year-strategic-plan\/","og_locale":"es_ES","og_type":"article","og_title":"North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce","og_description":"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.","og_url":"https:\/\/www.northcentralmass.com\/es\/north-central-massachusetts-announces-three-year-strategic-plan\/","og_site_name":"North Central Massachusetts Chamber of Commerce","article_publisher":"https:\/\/www.facebook.com\/ncmchamber","article_published_time":"2023-04-06T14:00:15+00:00","article_modified_time":"2025-02-02T23:27:41+00:00","og_image":[{"width":1200,"height":454,"url":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg","type":"image\/jpeg"}],"author":"northcentralmass","twitter_card":"summary_large_image","twitter_creator":"@ncmchamber","twitter_site":"@ncmchamber","twitter_misc":{"Written by":"northcentralmass","Est. reading time":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#article","isPartOf":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/"},"author":{"name":"northcentralmass","@id":"https:\/\/www.northcentralmass.com\/#\/schema\/person\/d8d3caef0152a831fa2ddb493f900037"},"headline":"North Central Massachusetts announces three-year strategic plan","datePublished":"2023-04-06T14:00:15+00:00","dateModified":"2025-02-02T23:27:41+00:00","mainEntityOfPage":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/"},"wordCount":488,"publisher":{"@id":"https:\/\/www.northcentralmass.com\/#organization"},"image":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg","articleSection":["Chamber News"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/","url":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/","name":"North Central Massachusetts announces three-year strategic plan &#187; North Central Massachusetts Chamber of Commerce","isPartOf":{"@id":"https:\/\/www.northcentralmass.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#primaryimage"},"image":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#primaryimage"},"thumbnailUrl":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg","datePublished":"2023-04-06T14:00:15+00:00","dateModified":"2025-02-02T23:27:41+00:00","description":"The North Central Massachusetts Chamber of Commerce today announced a new strategic plan designed to build upon the considerable momentum generated through the keen vision and steady execution of their prior plan announced in 2018.","breadcrumb":{"@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#primaryimage","url":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg","contentUrl":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/04\/NCMCC-Strategic-Plan-2022.jpg","width":1200,"height":454,"caption":"NCMCC Strategic Plan 2022"},{"@type":"BreadcrumbList","@id":"https:\/\/www.northcentralmass.com\/north-central-massachusetts-announces-three-year-strategic-plan\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.northcentralmass.com\/home\/"},{"@type":"ListItem","position":2,"name":"North Central Massachusetts announces three-year strategic plan"}]},{"@type":"WebSite","@id":"https:\/\/www.northcentralmass.com\/#website","url":"https:\/\/www.northcentralmass.com\/","name":"C\u00e1mara de Comercio del Norte Central de Massachusetts","description":"","publisher":{"@id":"https:\/\/www.northcentralmass.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.northcentralmass.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.northcentralmass.com\/#organization","name":"C\u00e1mara de Comercio del Norte Central de Massachusetts","url":"https:\/\/www.northcentralmass.com\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.northcentralmass.com\/#\/schema\/logo\/image\/","url":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/09\/nccc-yoast-logo.jpg","contentUrl":"https:\/\/www.northcentralmass.com\/wp-content\/uploads\/2023\/09\/nccc-yoast-logo.jpg","width":1200,"height":600,"caption":"North Central Massachusetts Chamber of Commerce"},"image":{"@id":"https:\/\/www.northcentralmass.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ncmchamber","https:\/\/x.com\/ncmchamber","https:\/\/www.linkedin.com\/groups\/North-Central-Massachusetts-Chamber-Commerce-8253188\/about"]},{"@type":"Person","@id":"https:\/\/www.northcentralmass.com\/#\/schema\/person\/d8d3caef0152a831fa2ddb493f900037","name":"Noroeste de Massachusetts","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6370a45ced61e8133cbb8b5a4d9728fcdb76cfeb5dd922ed77ef535c4df722c9?s=96&d=mm&r=g","caption":"northcentralmass"},"url":"https:\/\/www.northcentralmass.com\/es\/author\/northcentralmass\/"}]}},"_links":{"self":[{"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/posts\/18727","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/comments?post=18727"}],"version-history":[{"count":0,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/posts\/18727\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/media\/18730"}],"wp:attachment":[{"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/media?parent=18727"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/categories?post=18727"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.northcentralmass.com\/es\/wp-json\/wp\/v2\/tags?post=18727"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}